{"id":1278,"count":3,"description":"","link":"https:\/\/stl.tech\/de\/category\/verwaltete-dienste\/","name":"Verwaltete Dienste","slug":"verwaltete-dienste","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verwaltete Dienste Archives - STL Tech<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verwaltete Dienste Archives - STL Tech\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stl.tech\/de\/category\/verwaltete-dienste\/\" \/>\n<meta property=\"og:site_name\" content=\"STL Tech\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@STL_tech\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/stl.tech\\\/de\\\/category\\\/verwaltete-dienste\\\/\",\"url\":\"https:\\\/\\\/stl.tech\\\/de\\\/category\\\/verwaltete-dienste\\\/\",\"name\":\"Verwaltete Dienste Archives - STL Tech\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stl.tech\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stl.tech\\\/de\\\/category\\\/verwaltete-dienste\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stl.tech\\\/de\\\/category\\\/verwaltete-dienste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stl.tech\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verwaltete Dienste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stl.tech\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/stl.tech\\\/de\\\/\",\"name\":\"STL Tech\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/stl.tech\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stl.tech\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stl.tech\\\/de\\\/#organization\",\"name\":\"STL Tech\",\"url\":\"https:\\\/\\\/stl.tech\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stl.tech\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stl.tech\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/stl2_logo.png\",\"contentUrl\":\"https:\\\/\\\/stl.tech\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/stl2_logo.png\",\"width\":119,\"height\":40,\"caption\":\"STL Tech\"},\"image\":{\"@id\":\"https:\\\/\\\/stl.tech\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/STL-Sterlite-Technologies-Limited\\\/100064100861804\\\/\",\"https:\\\/\\\/x.com\\\/STL_tech\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sterlite-technologies-ltd-\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verwaltete Dienste Archives - STL Tech","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Verwaltete Dienste Archives - STL Tech","og_url":"https:\/\/stl.tech\/de\/category\/verwaltete-dienste\/","og_site_name":"STL Tech","twitter_card":"summary_large_image","twitter_site":"@STL_tech","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/stl.tech\/de\/category\/verwaltete-dienste\/","url":"https:\/\/stl.tech\/de\/category\/verwaltete-dienste\/","name":"Verwaltete Dienste Archives - STL Tech","isPartOf":{"@id":"https:\/\/stl.tech\/de\/#website"},"breadcrumb":{"@id":"https:\/\/stl.tech\/de\/category\/verwaltete-dienste\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/stl.tech\/de\/category\/verwaltete-dienste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stl.tech\/de\/"},{"@type":"ListItem","position":2,"name":"Verwaltete Dienste"}]},{"@type":"WebSite","@id":"https:\/\/stl.tech\/de\/#website","url":"https:\/\/stl.tech\/de\/","name":"STL Tech","description":"","publisher":{"@id":"https:\/\/stl.tech\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stl.tech\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/stl.tech\/de\/#organization","name":"STL Tech","url":"https:\/\/stl.tech\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stl.tech\/de\/#\/schema\/logo\/image\/","url":"https:\/\/stl.tech\/wp-content\/uploads\/2022\/10\/stl2_logo.png","contentUrl":"https:\/\/stl.tech\/wp-content\/uploads\/2022\/10\/stl2_logo.png","width":119,"height":40,"caption":"STL Tech"},"image":{"@id":"https:\/\/stl.tech\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/STL-Sterlite-Technologies-Limited\/100064100861804\/","https:\/\/x.com\/STL_tech","https:\/\/www.linkedin.com\/company\/sterlite-technologies-ltd-\/"]}]}},"_links":{"self":[{"href":"https:\/\/stl.tech\/de\/wp-json\/wp\/v2\/categories\/1278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stl.tech\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/stl.tech\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/stl.tech\/de\/wp-json\/wp\/v2\/posts?categories=1278"},{"href":"https:\/\/stl.tech\/de\/wp-json\/wp\/v2\/resource-enquiry?categories=1278"},{"href":"https:\/\/stl.tech\/de\/wp-json\/wp\/v2\/stl-media-coverage?categories=1278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}